{"id":112,"count":16,"description":"\n<strong><em>Num\u00e9ro sp\u00e9cial\nHappening<\/strong><\/em>\n\n\nCe num\u00e9ro a \u00e9t\u00e9 compos\u00e9 par Denis Durand, avec des textes de Hem Day et de Marcel Viaud. Les traductions sont de Paul Semp\u00e9 et de DEnis Durand.\n\n\n<strong><a href=\"930\">L'originalit\u00e9 dans l'action<\/a><\/strong>\n\n <a href=\"931\">Le happening<\/a> (Marcel Viaud) <a href=\"932\">Le happening chez les provos<\/a> (Hem Day) <a href=\"933\">Parade, spectacle<\/a> (Michael Kustow) <a href=\"934\">&nbsp;(article sans titre)<\/a> <a href=\"935\">Flower power ou l'art de protester<\/a> <a href=\"936\">Aguigui<\/a>\n\n\n<strong><a href=\"937\">L'originalit\u00e9 dans le mouvement<\/a><\/strong>\n\n <a href=\"938\">Mouvement anti-atomique anglais<\/a> <a href=\"939\">Provos<\/a> <a href=\"940\">Les diggers<\/a> (Alex Forman) <a href=\"941\">Les hippies<\/a> <a href=\"942\">Une nouvelle gauche?<\/a> <a href=\"943\">La r\u00e9cup\u00e9ration<\/a> <a href=\"944\">Les marchands<\/a>\n\n\n<a href=\"945\">Conclusions provisoires<\/a> (Denis Durand)\n\n\n\n\n\n\n\n\n<strong>Happening<\/strong> : Manifestation spontan\u00e9e de cr\u00e9ativit\u00e9 collective qui rev\u00eat un caract\u00e8re provocant dans une soci\u00e9t\u00e9 hostile \u00e0 la cr\u00e9ativit\u00e9, et dans laquelle la police participe souvent comme partenaire au jeu. Un happening n\u2019est jamais \u00ab planifi\u00e9 \u00bb ni organis\u00e9, c\u2019est \u00e0 peine s\u2019il est pr\u00e9par\u00e9 ; en effet, personne ne peut pr\u00e9voir comment il se d\u00e9roulera, ni combien de provos et de policiers y participeront.\n\n\n<strong>Flower power<\/strong> : \u00ab Pacifisme, non-violence ; \u00e0 coup s\u00fbr. Ou encore : R\u00e9sistance plus Flower Power \u00e9gale R\u00e9volution. Le Flower Power est aussi quelque chose de gai. Si nous perdons notre sens de l\u2019humour et notre capacit\u00e9 d\u2019amour, si nous devenons amers, col\u00e9reux et durs, nous n\u2019avons rien \u00e0 offrir \u00e0 la soci\u00e9t\u00e9, aucune alternative au pr\u00e9sent. \u00bb","link":"https:\/\/la-presse-anarchiste.net\/index.php\/category\/anarchisme-et-non-violence-1965-1974\/anarchisme-et-non-violence-na11-12-janvier-fevrier-1968\/","name":"Anarchisme et non-violence n\u00b011-12 (janvier\/fevrier 1968)","slug":"anarchisme-et-non-violence-na11-12-janvier-fevrier-1968","taxonomy":"category","parent":17,"meta":[],"_links":{"self":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/categories\/112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/categories\/17"}],"wp:post_type":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts?categories=112"},{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/pages?categories=112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}