{"id":1424,"date":"2008-03-29T17:17:03","date_gmt":"2008-03-29T17:17:03","guid":{"rendered":"https:\/\/la-presse-anarchiste.net\/index.php\/2008\/03\/29\/jusqua-la-lie\/"},"modified":"2008-03-29T17:17:03","modified_gmt":"2008-03-29T17:17:03","slug":"jusqua-la-lie","status":"publish","type":"post","link":"https:\/\/la-presse-anarchiste.net\/index.php\/2008\/03\/29\/jusqua-la-lie\/","title":{"rendered":"Jusqu\u2019\u00e0 la&nbsp;lie"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/1424?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/la-presse-anarchiste.net\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Afficher le PDF\"><\/a><a href=\"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/1424?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/la-presse-anarchiste.net\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\"><\/a><\/div><p><strong>Sant\u2019 Andrea delle fratte<\/strong><br>\n&nbsp;<\/p>\n<poesie>De brique rose, avec l\u2019\u00e9lan<br>\nDes nudi\u00adt\u00e9s de ses pilastres,<br>\nEt puis tout en haut la corbeille<br>\nDe la cou\u00adronne sur le&nbsp;ciel.<br>\nDites Saint-Andr\u00e9-des-\u00abFratte&nbsp;\u00bb,<br>\nDites Saint-Andr\u00e9-des-Buissons,<br>\nEt c\u2019est dans la ville si vieille<br>\nEt sa pous\u00adsi\u00e8re, la campagne.<br>\nComme tant de choses \u00e0&nbsp;Rome<br>\nCe bibe\u00adlot de Borromine<br>\nEst bri\u00adco\u00adlage, mais grandeur.<br>\nParce qu\u2019elle fut \u00e9cossaise<br>\nOn r\u00eave de Nord et de&nbsp;rois.<br>\nEn la ville de tant d\u2019\u00e9glises<br>\nC\u2019est mon \u00e9glise. Pr\u00e9f\u00e9r\u00e9e.<br>\nCar elle fut notre voisine<br>\nEt le salut de nos matins<br>\nAux jours heu\u00adreux, aux jours enfuis\u2026<br>\nEt jamais je n\u2019y reviens seul.<br>\nL\u2019absente ici pr\u00e9\u00adsente, en&nbsp;moi<br>\nEn red\u00e9\u00adcouvre la pr\u00e9sence.<br>\nRose sou\u00adrire dans les larmes&nbsp;:<br>\nDe soleil et d\u2019ombre s\u2019abreuvent<br>\nDans le doux clo\u00eetre des minimes<br>\nLe puits, l\u2019\u00e9toile des all\u00e9es.<br>\nCimiers fun\u00e8bres, roses fra\u00eeches,<br>\nTout, cha\u00adri\u00adta\u00adble\u00adment, enivre<br>\nLe p\u00e8le\u00adrin, moins \u00e9tranger&nbsp;\u2014<br>\nSon chant le livre et le d\u00e9livre,<br>\nSon chant, pr\u00e9\u00adsent fait du&nbsp;pass\u00e9&nbsp;\u2014<br>\nAu noir mys\u00adt\u00e8re de survivre.<\/poesie>\n&nbsp;<br>\nRome, 14 mai&nbsp;1963\n<p><strong>Plus ton petit&nbsp;Lir\u00e9\u2026<\/strong><br>\n&nbsp;\n<poesie>Plus ton petit Lir\u00e9 sans gloire, du Bellay,<br>\nQue le mont Pala\u00adtin \u00e9tait cher \u00e0 ton&nbsp;\u00e2me&nbsp;;<br>\nMais dans Rome o\u00f9 l\u2019auto le dis\u00adpute \u00e0 l\u2019inf\u00e2me<br>\nPubli\u00adci\u00adt\u00e9, le tertre o\u00f9 fut le vieux palais,<br>\nSem\u00adblable \u00e0 nos ver\u00adgers, aujourd\u2019hui te plairait.<\/poesie>\n&nbsp;<br>\n<strong>Jusqu\u2019\u00e0 la&nbsp;lie<\/strong><br>\n&nbsp;\n<poesie>Un ciel d\u2019ouragan.<br>\nLe jour dure. A&nbsp;quand<br>\nLa fin du soleil&nbsp;?<br>\nTout jusqu\u2019\u00e0 la&nbsp;lie<br>\nFaut boire&nbsp;: la&nbsp;vie,<br>\nLa mort, c\u2019est pareil.<\/poesie>\n&nbsp;<br>\nJean Paul Samson<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sant\u2019 Andrea delle fratte &nbsp; De brique rose, avec l\u2019\u00e9lan Des nudi\u00adt\u00e9s de ses pilastres, Et puis tout en haut la cor\u00adbeille De la cou\u00adronne sur le&nbsp;ciel. Dites Saint-Andr\u00e9-des-\u00abFratte&nbsp;\u00bb, Dites Saint-Andr\u00e9-des-Buis\u00adsons, Et c\u2019est dans la ville si vieille Et sa pous\u00adsi\u00e8re, la cam\u00adpagne. Comme tant de choses \u00e0&nbsp;Rome Ce bibe\u00adlot de Bor\u00adro\u00admine Est bri\u00adco\u00adlage,&nbsp;mais&nbsp;[\u2026]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[157],"tags":[],"ppma_author":[540],"class_list":["post-1424","post","type-post","status-publish","format-standard","hentry","category-temoins-n33-ete-1963"],"authors":[{"term_id":540,"user_id":1,"is_guest":0,"slug":"admin_3gikpwyf","display_name":"Vincent Dubuc","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/d015720652c25fd2ced191ade86430094e1f288a17483713e3b34d26dea52507?s=96&d=mm&r=g","author_category":"","user_url":"https:\/\/la-presse-anarchiste.net","last_name":"Dubuc","first_name":"Vincent","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/1424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/comments?post=1424"}],"version-history":[{"count":0,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/1424\/revisions"}],"wp:attachment":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/media?parent=1424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/categories?post=1424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/tags?post=1424"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/ppma_author?post=1424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}