{"id":2924,"date":"1926-08-01T00:11:02","date_gmt":"1926-08-01T00:11:02","guid":{"rendered":"https:\/\/la-presse-anarchiste.net\/index.php\/2011\/07\/22\/les-internationales-dindustries-2\/"},"modified":"2025-07-15T14:16:49","modified_gmt":"2025-07-15T14:16:49","slug":"les-internationales-dindustries-2","status":"publish","type":"post","link":"https:\/\/la-presse-anarchiste.net\/index.php\/1926\/08\/01\/les-internationales-dindustries-2\/","title":{"rendered":"Les Internationales d\u2019Industries"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/2924?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/la-presse-anarchiste.net\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Afficher le PDF\"><\/a><a href=\"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/2924?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/la-presse-anarchiste.net\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\"><\/a><\/div><p>Nous appre\u00adnons qu\u2019au com\u00admen\u00adce\u00adment de juillet une r\u00e9union des d\u00e9l\u00e9\u00adgu\u00e9s des F\u00e9d\u00e9\u00adra\u00adtions du B\u00e2ti\u00adment de la Hol\u00adlande et de l\u2019Al\u00adle\u00admagne s\u2019est tenue \u00e0 D\u00fcs\u00adsel\u00addorf, en vue de pr\u00e9\u00adpa\u00adrer l\u2019or\u00adga\u00adni\u00adsa\u00adtion d\u2019une Inter\u00adna\u00adtio\u00adnale syn\u00addi\u00adca\u00adliste r\u00e9vo\u00adlu\u00adtion\u00adnaire des tra\u00advailleurs du B\u00e2ti\u00adment. Un comi\u00adt\u00e9 pro\u00advi\u00adsoire s\u2019y est cr\u00e9\u00e9 qui va bien\u00adt\u00f4t lan\u00adcer un appel \u00e0 toutes les orga\u00adni\u00adsa\u00adtions syn\u00addi\u00adca\u00adlistes r\u00e9vo\u00adlu\u00adtion\u00adnaires du B\u00e2ti\u00adment en vue d\u2019une Conf\u00e9\u00adrence inter\u00adna\u00adtio\u00adnale pro\u00adchaine ayant pour but de mettre sur pied un orga\u00adnisme unis\u00adsant, indus\u00adtriel\u00adle\u00adment, les tra\u00advailleurs du B\u00e2ti\u00adment de tous les&nbsp;pays.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous appre\u00adnons qu\u2019au com\u00admen\u00adce\u00adment de juillet une r\u00e9union des d\u00e9l\u00e9\u00adgu\u00e9s des F\u00e9d\u00e9\u00adra\u00adtions du B\u00e2ti\u00adment de la Hol\u00adlande et de l\u2019Al\u00adle\u00admagne s\u2019est tenue \u00e0 D\u00fcs\u00adsel\u00addorf, en vue de pr\u00e9\u00adpa\u00adrer l\u2019or\u00adga\u00adni\u00adsa\u00adtion d\u2019une Inter\u00adna\u00adtio\u00adnale syn\u00addi\u00adca\u00adliste r\u00e9vo\u00adlu\u00adtion\u00adnaire des tra\u00advailleurs du B\u00e2ti\u00adment. Un comi\u00adt\u00e9 pro\u00advi\u00adsoire s\u2019y est cr\u00e9\u00e9 qui va bien\u00adt\u00f4t lan\u00adcer un appel \u00e0 toutes les orga\u00adni\u00adsa\u00adtions syn\u00addi\u00adca\u00adlistes r\u00e9volutionnaires&nbsp;[\u2026]<\/p>\n","protected":false},"author":8,"featured_media":4959,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"wp-custom-template-page-d-article","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[354],"tags":[951],"ppma_author":[680],"class_list":["post-2924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-voix-du-travail-n1-aout-1926","tag-organisation-ouvriere"],"authors":[{"term_id":680,"user_id":8,"is_guest":0,"slug":"anonyme","display_name":"Anonyme","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/cdccebf2bbf18d75df96a6721f7ce7f7ec80d026f1b8ec6be93de563bca5236b?s=96&d=mm&r=g","author_category":"","user_url":"","last_name":"","first_name":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/2924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/comments?post=2924"}],"version-history":[{"count":3,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/2924\/revisions"}],"predecessor-version":[{"id":8821,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/2924\/revisions\/8821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/media\/4959"}],"wp:attachment":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/media?parent=2924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/categories?post=2924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/tags?post=2924"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/ppma_author?post=2924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}