{"id":944,"date":"1968-01-01T00:04:50","date_gmt":"1968-01-01T00:04:50","guid":{"rendered":"https:\/\/la-presse-anarchiste.net\/index.php\/2007\/10\/30\/parade-spectacle\/"},"modified":"2024-04-29T19:55:46","modified_gmt":"2024-04-29T19:55:46","slug":"parade-spectacle","status":"publish","type":"post","link":"https:\/\/la-presse-anarchiste.net\/index.php\/1968\/01\/01\/parade-spectacle\/","title":{"rendered":"Parade, spectacle"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/944?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/la-presse-anarchiste.net\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Afficher le PDF\"><\/a><a href=\"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/944?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/la-presse-anarchiste.net\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\"><\/a><\/div><p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">\u00ab&nbsp;En bref, je sug\u00adg\u00e8re que les mou\u00adve\u00adments paci\u00adfistes \u00e9lar\u00adgissent la d\u00e9fi\u00adni\u00adtion de la mani\u00adfes\u00adta\u00adtion pour qu\u2019elle com\u00adprenne des d\u00e9mons\u00adtra\u00adtions avec marion\u00adnettes g\u00e9antes, des hap\u00adpe\u00adnings, des spec\u00adtacles, des parades paci\u00adfistes&nbsp;\u00bb, \u00e9crit Michael Kus\u00adtow. En Grande-Bre\u00adtagne, la marche de P\u00e2ques 1966 se ter\u00admi\u00adna par un ras\u00adsem\u00adble\u00adment \u00e0 Tra\u00adfal\u00adgar Square et plus par\u00adti\u00adcu\u00adli\u00e8\u00adre\u00adment par un spec\u00adtacle de marion\u00adnettes g\u00e9antes dont Michael Kus\u00adtow fut l\u2019un des orga\u00adni\u00adsa\u00adteurs. Dans cet article (\u00ab&nbsp;Peace News&nbsp;\u00bb, 29 avril 1966), il d\u00e9crit les peines et les joies qui accom\u00adpa\u00adgn\u00e8rent la pr\u00e9\u00adpa\u00adra\u00adtion de ce spec\u00adtacle (o\u00f9 le cr\u00e2ne de Harold Wil\u00adson s\u2019ouvrait pour lais\u00adser para\u00eetre les acteurs de son cau\u00adche\u00admar&nbsp;: une fus\u00e9e nucl\u00e9aire pour la t\u00eate de John\u00adson, une botte pour celle de Ian Smith) \u2013 il d\u00e9crit ce spec\u00adtacle dans toutes ses dif\u00adfi\u00adcul\u00adt\u00e9s avec les\u00adquelles il s\u2019est d\u00e9bat\u00adtu \u2013, tout cela dans un style per\u00adson\u00adna\u00adli\u00ads\u00e9 qui nous per\u00admet de p\u00e9n\u00e9\u00adtrer le labeur qui a don\u00adn\u00e9 forme \u00e0 ce spec\u00adtacle. Il conclut&nbsp;: \u00ab&nbsp;Il y a une n\u00e9ces\u00adsi\u00adt\u00e9 urgente \u00e0 faire tom\u00adber les \u00e9cailles des yeux des gens&nbsp;; les res\u00adsources de l\u2019action, de la parole, de la cou\u00adleur, du son et de la musique arran\u00adg\u00e9es d\u2019une mani\u00e8re auda\u00adcieuse et pro\u00advo\u00adcante peuvent tou\u00adcher les nerfs et le c\u0153ur d\u2019une mani\u00e8re qu\u2019aucun argu\u00adment, qu\u2019aucune exhor\u00adta\u00adtion, employ\u00e9 seul, ne peut&nbsp;faire.&nbsp;\u00bb<\/p>\n<h5 lang=\"fr-FR\" style=\"text-align: center;\" align=\"justify\">\u2014 O \u2014<\/h5>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Cette d\u00e9mons\u00adtra\u00adtion de marion\u00adnettes g\u00e9antes \u00e0 Tra\u00adfal\u00adgar Square, le lun\u00addi de P\u00e2ques, c\u2019est moi qui l\u2019ai diri\u00adg\u00e9e et en par\u00adtie \u00e9crite&nbsp;; main\u00adte\u00adnant je vou\u00addrais en par\u00adler. Elle a lais\u00ads\u00e9 une grande tache rouge sur les pav\u00e9s de la North Ter\u00adrace, l\u00e0 o\u00f9 nous avons jet\u00e9 de la tein\u00adture \u00e0 l\u2019aniline rouge pour faire sourdre du sang sur le visage de H. Wil\u00adson, ramas\u00adsant en m\u00eame temps cette tein\u00adture dans nos che\u00adveux, nos yeux et sous nos ongles. Deux semaines plus tard, pas\u00adsant en auto\u00adbus, je peux encore voir des traces de cette tache. Deux semaines plus tard, toute cette entre\u00adprise ambi\u00adtieuse et folle laisse encore une trace dans mon esprit, un espoir dans mon&nbsp;c\u0153ur.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Nous avons r\u00e9us\u00adsi le coup&nbsp;: puisque des jour\u00adna\u00adlistes ont pr\u00e9\u00adf\u00e9\u00adr\u00e9 se pr\u00e9\u00adci\u00adpi\u00adter pour prendre des pho\u00adtos de har\u00adc\u00e8\u00adle\u00adment des agents ou de bagarres (com\u00admu\u00adn\u00e9\u00adment appe\u00adl\u00e9es \u00ab&nbsp;\u00e9chauf\u00adfou\u00adr\u00e9es&nbsp;\u00bb). Je d\u00e9sire que vous sachiez ce qui s\u2019est pas\u00ads\u00e9 en r\u00e9a\u00adli\u00adt\u00e9. Parce que, outre les empoi\u00adgnades autour du micro et les ques\u00adtions \u00e0 br\u00fble-pour\u00adpoint, outre les beu\u00adgle\u00adments, les pleurs, la col\u00e8re et les insultes du ras\u00adsem\u00adble\u00adment de cette ann\u00e9e, il me semble que quelque chose d\u2019autre est arri\u00adv\u00e9&nbsp;; et cela, si nous savons le faire cro\u00eetre, contient de grandes pos\u00adsi\u00adbi\u00adli\u00adt\u00e9s pour nous tous qui vivons pour la paix, la liber\u00adt\u00e9, l\u2019amour, la non-vio\u00adlence, la trans\u00adfor\u00adma\u00adtion, un monde nou\u00adveau, pour mon\u00adtrer notre propre \u00e9ti\u00adquette ch\u00e9\u00adrie, pres\u00adcrire notre propre foi v\u00e9ridique.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Le CND deman\u00adda \u00e0 Adrian Mit\u00adchell, po\u00e8te, \u00e0 Sal\u00adly Jacobs, des\u00adsi\u00adna\u00adtrice, et \u00e0 moi-m\u00eame d\u2019inventer une mani\u00adfes\u00adta\u00adtion spec\u00adta\u00adcu\u00adlaire pour conclure la marche de 1966. Tr\u00e8s bien, mais que devait-ce \u00eatre&nbsp;? \u00ab&nbsp;Beau\u00adcoup d\u2019entre nous ont d\u00fb, par\u00adfois, res\u00adsen\u00adtir un d\u00e9sir puis\u00adsant de contrer quelque acte de vio\u00adlence par\u00adti\u00adcu\u00adli\u00e8\u00adre\u00adment exces\u00adsif par des repr\u00e9\u00adsailles encore plus grandes et plus exces\u00adsives&nbsp;\u00bb, dit John Arden. Tous les trois, nous par\u00adta\u00adgions cette impul\u00adsion&nbsp;; nous d\u00e9si\u00adrions r\u00e9pli\u00adquer selon notre mani\u00e8re propre, cr\u00e9er quelque chose qui r\u00e9un\u00eet 15 000 per\u00adsonnes dans un seul mou\u00adve\u00adment de d\u00e9fi et d\u2019inqui\u00e9tude, quelque chose qui hur\u00adl\u00e2t, qui chan\u00adt\u00e2t, qui br\u00fb\u00adl\u00e2t les \u00e9tapes vers le but avec une flamme pure \u2013 non celle du napalm.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Nous explo\u00adr\u00e2mes les pr\u00e9\u00adc\u00e9\u00addents. Les dizaines de mil\u00adliers de Chi\u00adnois mani\u00adfes\u00adtant \u00e0 P\u00e9kin, mar\u00adchant et rou\u00adlant dans une impec\u00adcable sym\u00e9\u00adtrie, r\u00e9p\u00e9\u00adt\u00e9e avec pr\u00e9\u00adci\u00adsion. Refu\u00ads\u00e9e&nbsp;: la gym\u00adnique de masse n\u2019est pas bri\u00adtan\u00adnique et, fran\u00adche\u00adment, je ne voyais pas les mul\u00adti\u00adtudes \u00e9pui\u00ads\u00e9es s\u2019alignant vive\u00adment d\u2019elles-m\u00eames dans un signe CND math\u00e9\u00adma\u00adti\u00adque\u00adment par\u00adfait, apr\u00e8s trois dures jour\u00adn\u00e9es de marche dif\u00adfi\u00adcile. Mais il y avait dans l\u2019exemple chi\u00adnois quelque chose qui vous cou\u00adpait le souffle, quelque chose de beau que nous ne vou\u00adlions pas reje\u00adter&nbsp;: cela s\u2019exprima dans notre repr\u00e9\u00adsen\u00adta\u00adtion par l\u2019ondoiement des dra\u00adpeaux cou\u00adleur tur\u00adquoise et cerise, qui eut lieu au d\u00e9but. Les autres pr\u00e9\u00adc\u00e9\u00addents, les hap\u00adpe\u00adnings am\u00e9\u00adri\u00adcains, nous vou\u00adlions leur pou\u00advoir de choc, leur attrait qui se situait au-des\u00adsous du seuil du rai\u00adson\u00adne\u00adment. Les ras\u00adsem\u00adble\u00adments de Nurem\u00adberg&nbsp;: un aver\u00adtis\u00adse\u00adment contre les tra\u00adque\u00adnards du rituel et du c\u00e9r\u00e9\u00admo\u00adnial. Le gui\u00adgnol, la pan\u00adto\u00admime, le music-hall&nbsp;: on br\u00fble, c\u2019est presque cela.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Pour moi, ce qui d\u00e9clen\u00adcha la vision de la forme ultime de notre repr\u00e9\u00adsen\u00adta\u00adtion, ce fut le sui\u00adcide de Vicky. Quels que soient les motifs obs\u00adcurs qui l\u2019y condui\u00adsirent en d\u00e9fi\u00adni\u00adtive, son d\u00e9ses\u00adpoir devant la poli\u00adtique \u00e9tran\u00adg\u00e8re de Wil\u00adson lui ron\u00adgeait presque cer\u00adtai\u00adne\u00adment le c\u0153ur. Je vou\u00adlais que, de quelque mani\u00e8re, notre affaire f\u00fbt un hom\u00admage \u00e0 Vicky. Et, sou\u00addain, cela vint&nbsp;: ce que nous devions faire, c\u2019\u00e9tait emprun\u00adter et agran\u00addir les images que chaque des\u00adsi\u00adna\u00adteur \u2013 et Vicky mieux que la plu\u00adpart \u2013 avait employ\u00e9es. Ces images sont auda\u00adcieuses&nbsp;: elles com\u00adportent un sur\u00adr\u00e9a\u00adlisme intrin\u00ads\u00e8que (sou\u00adve\u00adnez-vous de Super-Mac ou de de Gaulle en poteaux t\u00e9l\u00e9\u00adgra\u00adphiques); elles sont tout de suite \u00e9lo\u00adquentes. Un des der\u00adniers des\u00adsins de Vicky mon\u00adtrait H. Wil\u00adson sui\u00advant L.B. John\u00adson sur un esca\u00adlier rou\u00adlant&nbsp;; il y avait sur les murs de la publi\u00adci\u00adt\u00e9 pour l\u2019escalade mili\u00adtaire au Viet\u00adnam&nbsp;; et l\u2019escalier por\u00adtait une cita\u00adtion d\u2019un dis\u00adcours de H. Wil\u00adson disant que le par\u00adti tra\u00advailliste n\u2019\u00e9tait rien d\u2019autre qu\u2019une croi\u00adsade morale. Mais le des\u00adsin ne n\u00e9ces\u00adsi\u00adtait pas d\u2019explications&nbsp;: la puis\u00adsance, la fureur des sen\u00adti\u00adments de Vicky appa\u00adraissent ind\u00e9\u00adnia\u00adble\u00adment dans l\u2019image m\u00eame de l\u2019escalier rou\u00adlant. Ce qu\u2019il nous fal\u00adlait pour com\u00admu\u00adni\u00adquer avec 15&nbsp;000 per\u00adsonnes dans le Square, c\u2019\u00e9tait cette m\u00eame qua\u00adli\u00adt\u00e9 d\u2019\u00e9vidente et d\u2019ind\u00e9niable v\u00e9ra\u00adci\u00adt\u00e9. Quelque chose que vous ne puis\u00adsiez manquer.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Sal\u00adly Jacobs dut aban\u00addon\u00adner parce qu\u2019elle avait trop de tra\u00advail. Jony Car\u00adru\u00adthers, un d\u00e9co\u00adra\u00adteur \u00e0 la barbe rousse, se pr\u00e9\u00adsen\u00adta, pro\u00adje\u00adta et des\u00adsi\u00adna les esquisses des per\u00adson\u00adnages de six m\u00e8tres, fit se mou\u00advoir les yeux, s\u2019ouvrir les bouches et son\u00adgea \u00e0 des d\u00e9tails tels que les \u00e9vents pour \u00e9vi\u00adter un d\u00e9sastre en cas de tem\u00adp\u00eate. Gerald Scarfe se pr\u00e9\u00adsen\u00adta, enthou\u00adsiaste \u00e0 l\u2019id\u00e9e d\u2019amplifier sa fan\u00adtai\u00adsie et sa bile aux dimen\u00adsions de Tra\u00adfal\u00adgar Square. Elaine Prans\u00adky, pro\u00adfes\u00adseur d\u2019art dra\u00adma\u00adtique, devint notre r\u00e9gis\u00adseur et com\u00admen\u00ad\u00e7a \u00e0 cher\u00adcher des cylindres d\u2019h\u00e9lium, d\u2019explorer les m\u00e9thodes pour faire des seaux de sang ou pour faire des nuages de fum\u00e9e sans feu. (R\u00e9ponses&nbsp;: de l\u2019eau bouillante sur de la glace s\u00e8che. Autres ques\u00adtions&nbsp;: o\u00f9 trou\u00adver de la glace un lun\u00addi de P\u00e2ques&nbsp;? Com\u00adment se pro\u00adcu\u00adrer des quan\u00adti\u00adt\u00e9s d\u2019eau bouillante sur North Ter\u00adrace au milieu d\u2019une foule turbulente?)<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Je deman\u00addai \u00e0 Peg\u00adgy Duff de m\u2019assurer une \u00e9quipe de trente per\u00adsonnes qua\u00adli\u00adfi\u00e9es, ou semi-qua\u00adli\u00adfi\u00e9es, pour faire la pein\u00adture de fond et r\u00e9p\u00e9\u00adter l\u2019op\u00e9ration des per\u00adson\u00adnages monstres. \u00c0 notre pre\u00admi\u00e8re ren\u00adcontre, il en vint six, dont deux seule\u00adment par le CND. J\u2019envisageai la catas\u00adtrophe, insis\u00adtai sur un effort d\u00e9ses\u00adp\u00e9\u00adr\u00e9 pour trou\u00adver des aides. Il est d\u00e9j\u00e0 assez dif\u00adfi\u00adcile de ras\u00adsem\u00adbler des gens volon\u00adtaires pour un tra\u00advail qu\u2019ils com\u00adprennent, la dif\u00adfi\u00adcul\u00adt\u00e9 est dou\u00adbl\u00e9e lorsque le tra\u00advail ne leur est pas familier.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Nous \u00e9tions rela\u00adti\u00adve\u00adment pri\u00advi\u00adl\u00e9\u00adgi\u00e9s, le CND nous garan\u00adtis\u00adsait 200 livres ster\u00adling pour payer les mat\u00e9\u00adriaux et l\u2019aide ext\u00e9\u00adrieure. (Ne p\u00e2lis\u00adsez pas&nbsp;: vous n\u2019avez pas besoin de 200 livres ster\u00adling pour cr\u00e9er votre repr\u00e9\u00adsen\u00adta\u00adtion, mais si vous devez r\u00e9a\u00adli\u00adser quelque chose d\u2019assez grand et d\u2019assez vivant pour frap\u00adper une audience sur une place publique, il vous faut des mat\u00e9\u00adriaux, de grandes sur\u00adfaces, du volume, de la gran\u00addeur \u2013 prier, emprun\u00adter ou per\u00adsua\u00adder, cepen\u00addant, peut aller loin.) Nous enga\u00adge\u00e2mes un char\u00adpen\u00adtier de th\u00e9\u00e2tre. Nous \u00e9tions en&nbsp;route.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Adrian et moi ter\u00admi\u00adn\u00e2mes le manus\u00adcrit une semaine avant P\u00e2ques.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Il com\u00adpre\u00adnait&nbsp;:<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">\u2013 Une intro\u00adduc\u00adtion \u2013 fan\u00adfare, dra\u00adpeaux et quelqu\u2019un qui harangue la&nbsp;foule&nbsp;;<br> \u2013 Un rap\u00adpel sur\u00adr\u00e9a\u00adliste des r\u00e9sul\u00adtats des \u00e9lec\u00adtions \u00e0 la&nbsp;TV&nbsp;;<br> \u2013 Wil\u00adson chan\u00adtant la paro\u00addie de \u00ab&nbsp;J\u00e9ru\u00adsa\u00adlem&nbsp;\u00bb d\u2019Adrian (\u00ab&nbsp;Je n\u2019abandonnerai pas mon cafouillage, je ne lais\u00adse\u00adrai pas mon poste glis\u00adser des mains, tant que nous n\u2019aurons pas construit le Penta\u00adgone sur la terre riche et pour\u00adris\u00adsante d\u2019Angleterre&nbsp;\u00bb);<br> \u2013 Une conver\u00adsa\u00adtion t\u00e9l\u00e9\u00adpho\u00adnique de Wil\u00adson avec une femme, qui se trouve \u00eatre la&nbsp;reine&nbsp;;<br> \u2013 Les Trois Sages (Smith, Banque d\u2019Angleterre, L.B.J.) por\u00adtant cadeaux et f\u00e9licitations&nbsp;;<br> \u2013 Inci\u00adta\u00adtion de Wil\u00adson \u00e0 la foule (\u00ab&nbsp;M\u2019aimez-vous&nbsp;?&nbsp;\u00bb) expri\u00adm\u00e9e sur les refrains de Tin\u00adker Bell et Billy Cotton&nbsp;;<br> \u2013 Cau\u00adche\u00admar de Wilson&nbsp;;<br> \u2013 En final, un chant tran\u00adquille d\u2019Isla Cameron.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Je tiens \u00e0 pr\u00e9\u00adci\u00adser que ce manus\u00adcrit \u00e9tait enti\u00e8\u00adre\u00adment l\u2019expression de ce que Adrian et moi d\u00e9si\u00adrions dire sur la situa\u00adtion actuelle. Il n\u2019\u00e9tait en rien gui\u00add\u00e9 ou influen\u00adc\u00e9 par le CND. Celui-ci nous a fait confiance. Nous avons r\u00e9a\u00adli\u00ads\u00e9 quelque chose de per\u00adson\u00adnel qui, je l\u2019esp\u00e8re, a r\u00e9us\u00adsi \u00e0 par\u00adler \u00e0 sa mani\u00e8re \u00e0 la plu\u00adpart des mar\u00adcheurs. (Inci\u00addem\u00adment, il serait tr\u00e8s int\u00e9\u00adres\u00adsant pour nous de conna\u00eetre les r\u00e9ac\u00adtions des gens devant ce spec\u00adtacle.) De North Ter\u00adrace, nous pou\u00advions voir que les gens fai\u00adsaient atten\u00adtion, mais il \u00e9tait impos\u00adsible de savoir ce que tout cela signi\u00adfiait pour eux. Pour\u00adquoi ne pas \u00e9crire \u00e0 \u00ab&nbsp;Peace News&nbsp;\u00bb sur la pr\u00e9\u00adsen\u00adta\u00adtion de per\u00adson\u00adnages et aus\u00adsi sur les pour et les contre du repor\u00adtage&nbsp;?<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--expands-on-desktop \" data-mfn=\"1\" data-mfn-post-scope=\"000000003174e2030000000078e18905_944\"><a href=\"javascript:void(0)\" role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-000000003174e2030000000078e18905_944-1\">1<\/a><\/sup><span id=\"mfn-content-000000003174e2030000000078e18905_944-1\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"1\">Dick Wil\u00adcocks, des \u00ab&nbsp;Jeunes du CND&nbsp;\u00bb, \u00e9crit dans \u00ab&nbsp;Peace New&nbsp;\u00bb (6 mai 1966): \u00ab&nbsp;Je trou\u00advais les ras\u00adsem\u00adble\u00adments des ann\u00e9es pr\u00e9\u00adc\u00e9\u00addentes p\u00e9ni\u00adble\u00adment bar\u00adbants&nbsp;: ora\u00adteurs apr\u00e8s ora\u00adteurs nous rab\u00e2\u00adchaient leurs fra\u00adter\u00adnels saluts, exhor\u00adtaient et balan\u00ad\u00e7aient des opi\u00adnions qui p\u00e8tent sec \u00e0 une foule d\u00e9j\u00e0 conver\u00adtie. Ce genre de trai\u00adte\u00adment est sus\u00adcep\u00adtible de d\u00e9cou\u00adra\u00adger les gens qui se trouvent sur la route depuis trois jours. Nous avons eu un par\u00adle\u00admen\u00adtaire et divers autres ora\u00adteurs cette ann\u00e9e, mais quelque chose de jeune et de nou\u00adveau s\u2019est \u00e9ga\u00adle\u00adment pro\u00adduit&nbsp;: j\u2019ai sui\u00advi des yeux les marion\u00adnettes \u00e0 par\u00adtir du Square et j\u2019ai remar\u00adqu\u00e9 que tout le monde pr\u00e8s de moi les obser\u00advait avec atten\u00adtion. Pen\u00addant les dis\u00adcours tra\u00addi\u00adtion\u00adnels les gens res\u00adtent par d\u00e9f\u00e9\u00adrence, l\u2019expression bru\u00admeuse, l\u2019esprit occu\u00adp\u00e9 par les tasses de th\u00e9 et les bains \u00e0 la mou\u00adtarde \u2013 posent des ques\u00adtions et poussent des sif\u00adfle\u00adments quand ils pensent que c\u2019est appro\u00adpri\u00e9, parlent ou vendent des jour\u00adnaux. Le spec\u00adtacle de marion\u00adnettes tint la foule tran\u00adquille. [\u2026] Le tra\u00advail d\u2019\u00e9quipe et l\u2019effort spon\u00adta\u00adn\u00e9 qui entr\u00e8rent de mani\u00e8re effec\u00adtive en ligne de compte ont d\u00fb \u00eatre remar\u00adqu\u00e9s. [\u2026] La plu\u00adpart du spec\u00adtacle fut satis\u00adfai\u00adsant, ani\u00adm\u00e9 et tr\u00e8s vivant.&nbsp;\u00bb<\/span><\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Apr\u00e8s avoir cou\u00adp\u00e9 et r\u00e9duit notre manus\u00adcrit, nous pen\u00adsions avoir \u00e9crit ce que nous vou\u00adlions&nbsp;: quelque chose qui par\u00adtait de l\u2019iconoclasme (genre de la bande des\u00adsi\u00adn\u00e9e \u00ab&nbsp;Pri\u00advate Eye&nbsp;\u00bb), conti\u00adnuait par une gra\u00adda\u00adtion, plus sombre, plus hor\u00adri\u00adfiante, se ter\u00admi\u00adnait de mani\u00e8re plus calme, plus ferme par un chant. C\u2019est cette der\u00adni\u00e8re par\u00adtie qui nous don\u00adna le plus de dif\u00adfi\u00adcul\u00adt\u00e9s&nbsp;: o\u00f9 trou\u00adver un chant qui expri\u00adm\u00e2t l\u2019acceptation pleine et enti\u00e8re, \u00e0 la foi du d\u00e9ses\u00adpoir et de l\u2019espoir de notre situa\u00adtion actuelle&nbsp;? Apr\u00e8s avoir cher\u00adch\u00e9 en vain pen\u00addant des semaines, Isla Came\u00adron r\u00e9so\u00adlut le pro\u00adbl\u00e8me avec \u00ab&nbsp;Turn, turn, turn&nbsp;\u00bb, inter\u00adpr\u00e9\u00adta\u00adtion par Pete See\u00adger d\u2019un cha\u00adpitre de l\u2019Eccl\u00e9siaste&nbsp;: \u00ab&nbsp;Pour toutes choses, tour\u00adnez, tour\u00adnez, tour\u00adnez, il y a une sai\u00adson et un temps pour chaque des\u00adsein en ce&nbsp;monde.&nbsp;\u00bb<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Dans le sein humide et sombre de Round House (une r\u00e9plique du Centre, 42, du Albert Hall), nous com\u00admen\u00ad\u00e7\u00e2mes de peindre et de r\u00e9p\u00e9\u00adter dix jours avant P\u00e2ques. Ce qui s\u2019est pas\u00ads\u00e9 pen\u00addant ces dix jours est, je pense, l\u2019aspect le plus valable et le plus r\u00e9con\u00adfor\u00adtant de toute l\u2019affaire. Pen\u00addant ces dix jours, qua\u00adrante per\u00adsonnes apprirent \u00e0 col\u00adla\u00adbo\u00adrer les unes avec les autres, \u00e0 accep\u00adter une dis\u00adci\u00adpline de groupe, \u00e0 se fier les unes aux autres, li\u00e9es par une entre\u00adprise com\u00admune et par\u00adta\u00adg\u00e9e, en laquelle elles durent d\u2019abord croire et qu\u2019elles finirent par sou\u00adte\u00adnir et cr\u00e9er elles-m\u00eames.<\/p>\n<h5 lang=\"fr-FR\" style=\"text-align: center;\" align=\"justify\">\u2014 O \u2014<\/h5>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Silence dans le Square quand nous com\u00admen\u00ad\u00e7\u00e2mes. Pas de ques\u00adtion vous ne ques\u00adtion\u00adnez pas un per\u00adson\u00adnage de six m\u00e8tres. De la ter\u00adrasse de North Ter\u00adrace, je vois un par\u00adterre de visages atten\u00adtifs, fix\u00e9s sur nos g\u00e9ants noir et blanc. Au-des\u00adsus de la balus\u00adtrade, on lit notre ban\u00adde\u00adrole&nbsp;: \u00ab&nbsp;THE WHORE GAME&nbsp;\u00bb<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--expands-on-desktop \" data-mfn=\"2\" data-mfn-post-scope=\"000000003174e2030000000078e18905_944\"><a href=\"javascript:void(0)\" role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-000000003174e2030000000078e18905_944-2\">2<\/a><\/sup><span id=\"mfn-content-000000003174e2030000000078e18905_944-2\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"2\">Jeu de mots intra\u00addui\u00adsible en fran\u00ad\u00e7ais, signi\u00adfie&nbsp;: \u00ab&nbsp;jeu de putains&nbsp;\u00bb et se pro\u00adnonce comme \u00ab&nbsp;the war game&nbsp;\u00bb \u2013 \u00ab&nbsp;jeu de la guerre&nbsp;\u00bb.<\/span>. Il y a des sou\u00adrires sur tous les visages et les acteurs proches de moi, les machi\u00adnistes pr\u00eats \u00e0 faire rou\u00adler leurs pan\u00adtins, tous nous r\u00e9a\u00adli\u00adsons que nous tenons l\u2019attention du public, que nous com\u00admen\u00ad\u00e7ons \u00e0 per\u00adcer, \u00e0 prendre l\u2019opinion. Davan\u00adtage de rires&nbsp;: le gag de Ver\u00adwoerd, l\u2019histoire de Siniavs\u00adky et Daniel touchent juste. Nous regret\u00adtons de n\u2019avoir pas pu pla\u00adcer mieux les haut-par\u00adleurs&nbsp;: nous ne pen\u00adsons pas que tout le monde puisse entendre. Mais per\u00adsonne ne peut s\u2019arr\u00eater de regarder.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Rires et applau\u00addis\u00adse\u00adments appa\u00adraissent dis\u00adtants. Les acteurs ont bien sai\u00adsi le chro\u00adno\u00adm\u00e9\u00adtrage n\u00e9ces\u00adsaire de leurs par\u00adties, nous sui\u00advons les points sur le sc\u00e9\u00adna\u00adrio&nbsp;; la chose est bien lan\u00adc\u00e9e et ne coule pas. Main\u00adte\u00adnant, nous en venons au cau\u00adche\u00admar. Nous ouvrons la t\u00eate de Harold comme un \u0153uf et un b\u00e9b\u00e9 rose appa\u00adra\u00eet \u00e0 l\u2019int\u00e9rieur, criant tout ce qu\u2019il peut. Harold se lance dans une lita\u00adnie d\u00e9ses\u00adp\u00e9\u00adr\u00e9e, \u00e9nu\u00adm\u00e9\u00adrant tout ce qu\u2019aura ce b\u00e9b\u00e9 et pour\u00adquoi il pleure. C\u2019est ici qu\u2019il y a la glus longue suite de phrases de la pi\u00e8ce&nbsp;: est-ce que \u00e7a pour\u00adra aller&nbsp;? Au milieu du cat\u00e9\u00adchisme du pauvre et du riche, un ques\u00adtion\u00adneur s\u2019\u00e9crie&nbsp;: \u00ab&nbsp;Qu\u2019est-ce que cela a \u00e0 faire avec le CND&nbsp;?&nbsp;\u00bb Tout, je pense&nbsp;; si nous ne pou\u00advons pas relier notre pro\u00adtes\u00adta\u00adtion paci\u00adfiste avec une cri\u00adtique sociale, que fai\u00adsons-nous ici de toute mani\u00e8re&nbsp;?<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Je vois un pro\u00adfes\u00adseur applau\u00addir avec joie lorsque Harold en vient au pas\u00adsage qui parle d\u2019un \u00ab&nbsp;demi-bureau dans une classe de qua\u00adrante enfants, gar\u00ad\u00e7ons et filles, dans une pi\u00e8ce o\u00f9 c\u2019est tou\u00adjours novembre&nbsp;\u00bb. Quand le sang com\u00admence \u00e0 sourdre \u00e0 tra\u00advers les joues de Wil\u00adson et que le b\u00e9b\u00e9 s\u2019enflamme, un des plus chauds ques\u00adtion\u00adneurs s\u2019\u00e9crie&nbsp;: \u00ab&nbsp;D\u00e9go\u00fb\u00adtant.&nbsp;\u00bb Oui, ce l\u2019est cer\u00adtai\u00adne\u00adment&nbsp;! mais pour faire agir les gens afin de chan\u00adger des choses vilaines et d\u00e9go\u00fb\u00adtantes vous devez vous-m\u00eame vous sai\u00adsir d\u2019eux, vous les appro\u00adprier pour vos desseins.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Juste au moment o\u00f9 John Wells atteint le point culmi\u00adnant du cau\u00adche\u00admar fr\u00e9\u00adn\u00e9\u00adtique de Harold, un maniaque se sai\u00adsit du micro pr\u00e8s de moi et hurle&nbsp;: \u00ab&nbsp;Que Dieu b\u00e9nisse la Rho\u00add\u00e9\u00adsie&nbsp;!&nbsp;\u00bb Je me vois me sai\u00adsis\u00adsant de son poi\u00adgnet, essayant de lui faire l\u00e2cher le micro. Je ne me sens pas du tout violent&nbsp;: qu\u2019a cet idiot maniaque \u00e0 bri\u00adser l\u2019effort patient, soi\u00adgneux, col\u00adlec\u00adtif de cin\u00adquante per\u00adsonnes qui s\u2019efforcent de faire sor\u00adtir quelque ordre du chaos&nbsp;? De toutes les stu\u00adpi\u00addi\u00adt\u00e9s pos\u00adsibles, com\u00adment ce fou ose-t-il crier&nbsp;: \u00ab&nbsp;Que Dieu b\u00e9nisse la Rho\u00add\u00e9\u00adsie&nbsp;\u00bb&nbsp;? En fait, la prise de notre action \u00e9tait main\u00adte\u00adnant si forte que la plu\u00adpart des spec\u00adta\u00adteurs semblent avoir pris cela pour un autre \u00e9l\u00e9\u00adment du cau\u00adche\u00admar de Wil\u00adson&nbsp;: com\u00adpli\u00adment \u00e9qui\u00advoque de la poli\u00adtique \u00e9tran\u00adg\u00e8re de Wil\u00adson&nbsp;! Le voi\u00adci par\u00adti main\u00adte\u00adnant et je pousse Isla vers le micro pour chan\u00adter, plus t\u00f4t que pr\u00e9\u00advu. R\u00e9sul\u00adtat&nbsp;: sa voix calme, sans accom\u00adpa\u00adgne\u00adment, sort avec les sir\u00e8nes et les explo\u00adsions de notre bande sonore. Mais elle perce, claire et d\u00e9ten\u00addue, et, sou\u00addain, c\u2019est tout fini, calme, silence, sou\u00adla\u00adge\u00adment pro\u00addi\u00adgieux, la fum\u00e9e se dis\u00adsipe, nos bal\u00adlons flottent sur la place tra\u00ee\u00adnant les papiers argen\u00adt\u00e9s en forme de bombes. C\u2019est tout fini&nbsp;: nous com\u00admen\u00ad\u00e7ons \u00e0 nous dis\u00adper\u00adser. Jusqu\u2019\u00e0 P\u00e2ques prochain&nbsp;?<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Voi\u00adl\u00e0 com\u00adment c\u2019\u00e9tait vu par nous. Et, sou\u00addain, je sou\u00adhai\u00adtai conser\u00adver cette atmo\u00adsph\u00e8re de la fin, ce moment de com\u00adpr\u00e9\u00adhen\u00adsion, cet ins\u00adtant d\u2019assimilation et de r\u00e9flexion&nbsp;; je sou\u00adhai\u00adtai gar\u00adder ce sen\u00adti\u00adment, le faire reve\u00adnir encore et encore.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">C\u2019est pour\u00adquoi je vou\u00addrais recom\u00adman\u00adder que de telles mani\u00adfes\u00adta\u00adtions se repro\u00adduisent en plus grand nombre dans les mou\u00adve\u00adments paci\u00adfistes. Non pas seule\u00adment chaque ann\u00e9e sur le Square, mais chaque mois, chaque semaine dans chaque ville du pays. Cr\u00e9er le sens de l\u2019occasion, c\u2019est ce qu\u2019avaient fait les pre\u00admi\u00e8res marches et qu\u2019il faut retrou\u00adver. La foule aime les spec\u00adtacles publics gran\u00addioses&nbsp;: rel\u00e8ve de la Garde, le Tour\u00adnoi Royal, l\u2019ouverture du Par\u00adle\u00adment, les fun\u00e9\u00adrailles de Chur\u00adchill. Mais pour\u00adquoi tous les airs les meilleurs seraient-ils r\u00e9ser\u00adv\u00e9s au Diable&nbsp;?<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Bref, je sug\u00adg\u00e8re que le mou\u00adve\u00adment paci\u00adfiste \u00e9lar\u00adgisse la d\u00e9fi\u00adni\u00adtion de la mani\u00adfes\u00adta\u00adtion pour qu\u2019elle com\u00adprenne l\u2019exhibition de pan\u00adtins, des hap\u00adpe\u00adnings, du spec\u00adtacle, des parades pacifistes.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Il y a urgence \u00e0 \u00f4ter les \u00e9cailles des yeux des gens&nbsp;; et les res\u00adsources de l\u2019action, de la langue, de la cou\u00adleur, du son et de la musique, arran\u00adg\u00e9es de mani\u00e8re auda\u00adcieuse, pro\u00advo\u00adcante, peuvent tou\u00adcher les nerfs et le c\u0153ur, d\u2019une mani\u00e8re qu\u2019aucun argu\u00adment, aucune exhor\u00adta\u00adtion, employ\u00e9 seul ne peut faire. Notre prin\u00adcipe pour tout ce tra\u00advail devrait \u00eatre&nbsp;: Audace, Mer\u00adveilleux et Humour. Je pense qu\u2019il y a de nom\u00adbreux artistes, \u00e9cri\u00advains, acteurs, \u00e9di\u00adteurs pro\u00adfes\u00adsion\u00adnels qui sai\u00adsi\u00adraient cette occa\u00adsion de tra\u00advailler avec les groupes locaux volon\u00adtaires pour r\u00e9a\u00adli\u00adser un nou\u00adveau genre de spec\u00adtacle public sai\u00adsis\u00adsant et enga\u00adg\u00e9. Je parie que de nom\u00adbreuses villes pour\u00adraient four\u00adnir leur po\u00e8te, peintre, musi\u00adcien, acteur, \u00e9lec\u00adtri\u00adcien, char\u00adpen\u00adtier&nbsp;; et c\u2019est assez pour votre \u00e9quipe. Il faut seule\u00adment deman\u00adder aux professionnels.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Voyant le nombre crois\u00adsant de r\u00e9unions po\u00e9\u00adtiques, de clubs folk\u00adlo\u00adriques, nous savons que la ren\u00adcontre d\u2019un public vivant et d\u2019acteurs vivants peut pro\u00advo\u00adquer une com\u00admu\u00adni\u00adca\u00adtion pro\u00adfonde qui d\u00e9fie les men\u00adsonges et les demi-v\u00e9ri\u00adt\u00e9s de la presse et de la t\u00e9l\u00e9\u00advi\u00adsion. Qu\u2019attendons-nous&nbsp;? Le spec\u00adtacle de marion\u00adnettes de P\u00e2ques, cette ann\u00e9e, n\u2019est qu\u2019un d\u00e9but&nbsp;; il y a plu\u00adsieurs mani\u00e8res de dire la v\u00e9rit\u00e9.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">\u00c0 Tra\u00adfal\u00adgar Square, nous avons, \u00e0 tout le moins, lais\u00ads\u00e9 une marque sur les pav\u00e9s. Pou\u00advons-nous aller de l\u2019avant, sur\u00admon\u00adter l\u2019inefficacit\u00e9 \u00e9qui\u00advoque dans laquelle les masses nous ont plon\u00adg\u00e9s, inter\u00adve\u00adnir effec\u00adti\u00adve\u00adment dans la vie quo\u00adti\u00addienne des gens, et lais\u00adser une marque, un point d\u2019interrogation dans leurs c\u0153urs et leurs esprits&nbsp;? Le mou\u00adve\u00adment paci\u00adfiste a tou\u00adjours aim\u00e9 les anni\u00adver\u00adsaires signi\u00adfi\u00adca\u00adtifs. Le jour d\u2019Hiroshima se pr\u00e9\u00adsen\u00adte\u00adra \u00e0 nous dans quelques mois. Pour\u00adquoi ne pas le prendre pour un&nbsp;d\u00e9but&nbsp;?<\/p>\n<p lang=\"fr-FR\" style=\"text-align: right;\" align=\"justify\">Michael Kus\u00adtow<\/p>\n<ul class=\"modern-footnotes-list modern-footnotes-list--show-only-for-print\"><li><span>1<\/span><div>Dick Wil\u00adcocks, des \u00ab&nbsp;Jeunes du CND&nbsp;\u00bb, \u00e9crit dans \u00ab&nbsp;Peace New&nbsp;\u00bb (6 mai 1966): \u00ab&nbsp;Je trou\u00advais les ras\u00adsem\u00adble\u00adments des ann\u00e9es pr\u00e9\u00adc\u00e9\u00addentes p\u00e9ni\u00adble\u00adment bar\u00adbants&nbsp;: ora\u00adteurs apr\u00e8s ora\u00adteurs nous rab\u00e2\u00adchaient leurs fra\u00adter\u00adnels saluts, exhor\u00adtaient et balan\u00ad\u00e7aient des opi\u00adnions qui p\u00e8tent sec \u00e0 une foule d\u00e9j\u00e0 conver\u00adtie. Ce genre de trai\u00adte\u00adment est sus\u00adcep\u00adtible de d\u00e9cou\u00adra\u00adger les gens qui se trouvent sur la route depuis trois jours. Nous avons eu un par\u00adle\u00admen\u00adtaire et divers autres ora\u00adteurs cette ann\u00e9e, mais quelque chose de jeune et de nou\u00adveau s\u2019est \u00e9ga\u00adle\u00adment pro\u00adduit&nbsp;: j\u2019ai sui\u00advi des yeux les marion\u00adnettes \u00e0 par\u00adtir du Square et j\u2019ai remar\u00adqu\u00e9 que tout le monde pr\u00e8s de moi les obser\u00advait avec atten\u00adtion. Pen\u00addant les dis\u00adcours tra\u00addi\u00adtion\u00adnels les gens res\u00adtent par d\u00e9f\u00e9\u00adrence, l\u2019expression bru\u00admeuse, l\u2019esprit occu\u00adp\u00e9 par les tasses de th\u00e9 et les bains \u00e0 la mou\u00adtarde \u2013 posent des ques\u00adtions et poussent des sif\u00adfle\u00adments quand ils pensent que c\u2019est appro\u00adpri\u00e9, parlent ou vendent des jour\u00adnaux. Le spec\u00adtacle de marion\u00adnettes tint la foule tran\u00adquille. [\u2026] Le tra\u00advail d\u2019\u00e9quipe et l\u2019effort spon\u00adta\u00adn\u00e9 qui entr\u00e8rent de mani\u00e8re effec\u00adtive en ligne de compte ont d\u00fb \u00eatre remar\u00adqu\u00e9s. [\u2026] La plu\u00adpart du spec\u00adtacle fut satis\u00adfai\u00adsant, ani\u00adm\u00e9 et tr\u00e8s vivant.&nbsp;\u00bb<\/div><\/li><li><span>2<\/span><div>Jeu de mots intra\u00addui\u00adsible en fran\u00ad\u00e7ais, signi\u00adfie&nbsp;: \u00ab&nbsp;jeu de putains&nbsp;\u00bb et se pro\u00adnonce comme \u00ab&nbsp;the war game&nbsp;\u00bb \u2013 \u00ab&nbsp;jeu de la guerre&nbsp;\u00bb.<\/div><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>\u00ab&nbsp;En bref, je sug\u00adg\u00e8re que les mou\u00adve\u00adments paci\u00adfistes \u00e9lar\u00adgissent la d\u00e9fi\u00adni\u00adtion de la mani\u00adfes\u00adta\u00adtion pour qu\u2019elle com\u00adprenne des d\u00e9mons\u00adtra\u00adtions avec marion\u00adnettes g\u00e9antes, des hap\u00adpe\u00adnings, des spec\u00adtacles, des parades paci\u00adfistes&nbsp;\u00bb, \u00e9crit Michael Kus\u00adtow. En Grande-Bre\u00ad\u00adtagne, la marche de P\u00e2ques 1966 se ter\u00admi\u00adna par un ras\u00adsem\u00adble\u00adment \u00e0 Tra\u00adfal\u00adgar Square et plus par\u00adti\u00adcu\u00adli\u00e8\u00adre\u00adment par un spec\u00adtacle de marionnettes&nbsp;[\u2026]<\/p>\n","protected":false},"author":215,"featured_media":5488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"wp-custom-template-page-d-article","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[112],"tags":[],"ppma_author":[936],"class_list":["post-944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anarchisme-et-non-violence-na11-12-janvier-fevrier-1968"],"authors":[{"term_id":936,"user_id":215,"is_guest":0,"slug":"michael-kustow","display_name":"Michael Kustow","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5a1a5f1bea0aeb199668ed375bfa8e9420037a59532e354c0025fbe029c75875?s=96&d=mm&r=g","author_category":"","user_url":"","last_name":"Kustow","first_name":"Michael","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/users\/215"}],"replies":[{"embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/comments?post=944"}],"version-history":[{"count":4,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/944\/revisions"}],"predecessor-version":[{"id":7221,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/944\/revisions\/7221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/media\/5488"}],"wp:attachment":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/media?parent=944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/categories?post=944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/tags?post=944"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/ppma_author?post=944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}