{"id":951,"date":"1968-01-01T18:56:30","date_gmt":"1968-01-01T18:56:30","guid":{"rendered":"https:\/\/la-presse-anarchiste.net\/index.php\/2007\/10\/30\/les-diggers\/"},"modified":"2023-09-24T15:15:03","modified_gmt":"2023-09-24T15:15:03","slug":"les-diggers","status":"publish","type":"post","link":"https:\/\/la-presse-anarchiste.net\/index.php\/1968\/01\/01\/les-diggers\/","title":{"rendered":"Les diggers"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/951?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/la-presse-anarchiste.net\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Afficher le PDF\"><\/a><a href=\"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/951?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/la-presse-anarchiste.net\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\"><\/a><\/div><p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Quand un petit groupe d\u2019hommes com\u00admen\u00ad\u00e7a \u00e0 retour\u00adner (dig) la terre et \u00e0 plan\u00adter sur les ter\u00adrains com\u00admu\u00adnaux de St. Georges Hill dans le Sur\u00adrey en 1649, ce fut le point culmi\u00adnant et radi\u00adcal des nou\u00advelles forces de chan\u00adge\u00adment qui r\u00e9sul\u00adtaient de la R\u00e9forme dans l\u2019Empire Ger\u00adma\u00adnique. Car avec l\u2019effondrement de la supr\u00e9\u00adma\u00adtie totale de l\u2019\u00c9glise romaine, ces nou\u00advelles forces d\u00e9pas\u00adsaient la r\u00e9volte de Mar\u00adtin Luther. La des\u00adtruc\u00adtion de la rai\u00adson d\u2019\u00eatre de l\u2019omnipotence de l\u2019\u00c9glise condui\u00adsit le peuple jugu\u00adl\u00e9 \u00e0 mettre en ques\u00adtion le pou\u00advoir exer\u00adc\u00e9 par des formes autres de la struc\u00adture d\u2019autorit\u00e9 en d\u00e9ca\u00addence. Ceci peut mieux se voir dans la r\u00e9volte des pay\u00adsans dans l\u2019Empire ger\u00adma\u00adnique ain\u00adsi que dans la Guerre civile anglaise. Car non seule\u00adment l\u2019\u00c9glise \u00e9tait mise en ques\u00adtion, mais \u00e9ga\u00adle\u00adment les ins\u00adti\u00adtu\u00adtions de l\u2019\u00c9tat et le sys\u00adt\u00e8me de la pro\u00adpri\u00e9\u00adt\u00e9 des terres<sup class=\"modern-footnotes-footnote modern-footnotes-footnote--expands-on-desktop \" data-mfn=\"1\" data-mfn-post-scope=\"0000000002fe05b6000000005a6d099c_951\"><a href=\"javascript:void(0)\" role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-0000000002fe05b6000000005a6d099c_951-1\">1<\/a><\/sup><span id=\"mfn-content-0000000002fe05b6000000005a6d099c_951-1\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"1\">Docu\u00admen\u00adta\u00adtion de base dans \u00ab&nbsp;La Paix cr\u00e9a\u00adtrice&nbsp;\u00bb (tome II) de Bar\u00adth\u00e9\u00adle\u00admy de Ligt.<\/span>.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Les Dig\u00adgers \u2013 ce petit groupe d\u2019hommes ain\u00adsi connu \u2013 met\u00adtaient en ques\u00adtion l\u2019ordre exis\u00adtant dans sa tota\u00adli\u00adt\u00e9&nbsp;: ils avaient des griefs contre le cler\u00adg\u00e9, les juges, les hommes de loi, le par\u00adle\u00adment et les nobles. Ils reven\u00addi\u00adquaient que la terre com\u00admune, qui appar\u00adte\u00adnait au roi qui venait d\u2019\u00eatre ex\u00e9\u00adcu\u00adt\u00e9, soit remise au peuple. Le peuple pou\u00advait exploi\u00adter col\u00adlec\u00adti\u00adve\u00adment les ter\u00adrains com\u00admu\u00adnaux et \u00e9ta\u00adblir une r\u00e9pu\u00adblique bas\u00e9e sur la coop\u00e9\u00adra\u00adtion paral\u00adl\u00e8\u00adle\u00adment au sys\u00adt\u00e8me exis\u00adtant. Les Dig\u00adgers croyaient que leur sys\u00adt\u00e8me ferait preuve de tant de paix, de rai\u00adson et d\u2019amour que bien\u00adt\u00f4t le pays tout entier se join\u00addrait \u00e0 eux. Ils ne voyaient aucune n\u00e9ces\u00adsi\u00adt\u00e9 \u00e0 vio\u00adlence et refu\u00adsaient m\u00eame de se d\u00e9fendre s\u2019ils \u00e9taient attaqu\u00e9s.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Les Dig\u00adgers avaient deux argu\u00adments dis\u00adtincts pour leur cause, l\u2019un reli\u00adgieux et l\u2019autre poli\u00adtique. L\u2019argument reli\u00adgieux d\u00e9cla\u00adrait que Dieu n\u2019avait pas cr\u00e9\u00e9 la terre comme la jouis\u00adsance de quelques hommes seule\u00adment, mais plu\u00adt\u00f4t comme une richesse com\u00admune, pour tous. La pro\u00adpri\u00e9\u00adt\u00e9 de la terre avait \u00e9t\u00e9 acquise, depuis Guillaume le Conqu\u00e9\u00adrant, par l\u2019usage de l\u2019\u00e9p\u00e9e \u2013 indi\u00adrec\u00adte\u00adment quand ce n\u2019\u00e9tait pas direc\u00adte\u00adment. Cette pro\u00adpri\u00e9\u00adt\u00e9 de la terre bas\u00e9e sur le sang \u00e9tait immo\u00adrale. Les Dig\u00adgers croyaient que l\u2019homme avait deux ins\u00adtincts oppo\u00ads\u00e9s dans son esprit&nbsp;: la conser\u00adva\u00adtion de soi qui expli\u00adquait l\u2019avidit\u00e9 et la tue\u00adrie, et la conser\u00adva\u00adtion de la com\u00admu\u00adnau\u00adt\u00e9 que repr\u00e9\u00adsen\u00adtaient le par\u00adtage et l\u2019amour. Agir mora\u00adle\u00adment, cela signi\u00adfiait une vie bas\u00e9e sur la conser\u00adva\u00adtion de la com\u00admu\u00adnau\u00adt\u00e9. Les Dig\u00adgers croyaient \u00e9ga\u00adle\u00adment que si les hommes vivaient \u00e0 l\u2019heure actuelle en accord avec le prin\u00adcipe de conser\u00adva\u00adtion de la com\u00admu\u00adnau\u00adt\u00e9, leurs mau\u00advais ins\u00adtincts dis\u00adpa\u00adra\u00ee\u00adtraient \u00e0 cause du pou\u00advoir supr\u00eame de l\u2019amour universel.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">L\u2019argument poli\u00adtique des Dig\u00adgers \u00e9tait que, puisque la terre com\u00admune appar\u00adte\u00adnait autre\u00adfois au roi, elle appar\u00adte\u00adnait main\u00adte\u00adnant \u00e0 tous ceux qui avaient com\u00adbat\u00adtu pour mettre fin \u00e0 la monar\u00adchie. Donc, puisque les masses popu\u00adlaires avaient com\u00adbat\u00adtu, ces masses avaient des droits quant aux anciennes pos\u00adses\u00adsions royales. Il importe de remar\u00adquer que Gerald Wins\u00adtan\u00adley, le porte-parole prin\u00adci\u00adpal des Dig\u00adgers, mon\u00adtrait une ten\u00addance crois\u00adsante \u00e0 baser leur cause sur des argu\u00adments poli\u00adtiques plus concrets, pen\u00addant l\u2019histoire br\u00e8ve du mou\u00adve\u00adment. Le der\u00adnier docu\u00adment impor\u00adtant pro\u00adve\u00adnant du mou\u00adve\u00adment Dig\u00adger fut un long appel de Wins\u00adtan\u00adley \u00e0 Oli\u00adver Crom\u00adwell qui appe\u00adlait \u00e0 la cr\u00e9a\u00adtion en Angle\u00adterre d\u2019une r\u00e9pu\u00adblique bas\u00e9e sur la coop\u00e9\u00adra\u00adtion. Celui-ci com\u00adpre\u00adnait des pro\u00adpo\u00adsi\u00adtions concr\u00e8tes sur la mani\u00e8re d\u2019organiser l\u2019\u00e9conomie, les \u00e9coles, l\u2019\u00c9tat et le sys\u00adt\u00e8me judi\u00adciaire. Il sou\u00adte\u00adnait la pro\u00adpri\u00e9\u00adt\u00e9 pri\u00adv\u00e9e dans le cadre du foyer, la famille comme cel\u00adlule sociale, le suf\u00adfrage uni\u00adver\u00adsel chez les adultes, la pro\u00adpri\u00e9\u00adt\u00e9 com\u00admune de toutes les terres de la Cou\u00adronne et des entre\u00adp\u00f4ts com\u00admuns pour tous les produits.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Bien que les pre\u00admiers Dig\u00adgers n\u2019aient pas r\u00e9us\u00adsi dans leur but, leurs pen\u00ads\u00e9es ont sur\u00adv\u00e9\u00adcu par-des\u00adsus trois cents ann\u00e9es et r\u00e9ap\u00adpa\u00adraissent sous une forme remar\u00adqua\u00adble\u00adment sem\u00adblable. Sur\u00adgis\u00adsant d\u2019un \u00e9change de bons pro\u00adc\u00e9\u00add\u00e9s entre la Nou\u00advelle Gauche et l\u2019ancienne \u00ab&nbsp;beat g\u00e9n\u00e9\u00adra\u00adtion&nbsp;\u00bb, une culture hip\u00adpy a fleu\u00adri \u00e0 San Fran\u00adcis\u00adco fin 1965. Deux nou\u00adveaux fac\u00adteurs qui ont fait de cette semence hip\u00adpy un ph\u00e9\u00adno\u00adm\u00e8ne tr\u00e8s dis\u00adtinct \u00e9taient&nbsp;: pre\u00admi\u00e8\u00adre\u00adment, un sen\u00adti\u00adment de com\u00admu\u00adnau\u00adt\u00e9 (accen\u00adtu\u00e9 par des indi\u00advi\u00addus frus\u00adtr\u00e9s par la Nou\u00advelle Gauche), et deuxi\u00e8\u00adme\u00adment, l\u2019usage du LSD. Fran\u00adchis\u00adsant les dif\u00adf\u00e9\u00adrences \u00e9co\u00adno\u00admiques et sociales de beau\u00adcoup de ces Am\u00e9\u00adri\u00adcains \u00ab&nbsp;ali\u00e9\u00adn\u00e9s&nbsp;\u00bb, pour la plu\u00adpart tout jeunes, une \u00ab&nbsp;g\u00e9n\u00e9\u00adra\u00adtion de l\u2019amour&nbsp;\u00bb nou\u00advelle, tri\u00adbale, prit racine dans Haight-Ash\u00adbu\u00adry, dis\u00adtrict de cette ville. La nou\u00advelle force, d\u00e9cha\u00ee\u00adn\u00e9e par le LSD, consti\u00adtuait le fac\u00adteur pre\u00admier d\u2019unification d\u2019un groupe qui s\u2019\u00e9tendait de la clique moto\u00adcy\u00adcliste des Hell\u2019s Angels quel\u00adque\u00adfois vio\u00adlents aux boud\u00addhistes Zen qui m\u00e9ditent. Cette nou\u00advelle flo\u00adrai\u00adson fut au d\u00e9but amorphe, mais elle prit bien\u00adt\u00f4t la forme d\u2019une com\u00admu\u00adnau\u00adt\u00e9 boh\u00e8me com\u00adpl\u00e8te avec sa propre classe mar\u00adchande&nbsp;: les mar\u00adchands du \u00ab&nbsp;hip&nbsp;\u00bb.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">La nou\u00advelle com\u00admu\u00adnau\u00adt\u00e9 d\u2019amour de Haight-Ash\u00adbu\u00adry tirait ses membres prin\u00adci\u00adpa\u00adle\u00adment des rangs gros\u00adsis\u00adsants des jeunes gens \u00ab&nbsp;ali\u00e9\u00adn\u00e9s&nbsp;\u00bb qui fai\u00adsaient \u00e9ga\u00adle\u00adment connais\u00adsance avec le \u00ab&nbsp;voyage de l\u2019amour&nbsp;\u00bb (\u00ab&nbsp;love trip&nbsp;\u00bb). Dans les rues de Haight-Ash\u00adbu\u00adry, les conver\u00adsa\u00adtions se rem\u00adplis\u00adsaient de paroles d\u2019amour, et c\u2019est alors qu\u2019apparut sou\u00addai\u00adne\u00adment en automne 1966 un groupe s\u2019appelant les Dig\u00adgers. Ils com\u00admen\u00adc\u00e8rent par dis\u00adtri\u00adbuer de la nour\u00adri\u00adture dans le parc local \u2013 nour\u00adri\u00adture don\u00adn\u00e9e par des indi\u00advi\u00addus et r\u00e9col\u00adt\u00e9e des sur\u00adplus des mar\u00adch\u00e9s locaux. Le nou\u00adveau groupe essayait \u00e9ga\u00adle\u00adment de four\u00adnir le moyen de se loger aux jeunes en nombre crois\u00adsant qui \u00e9taient convain\u00adcus qu\u2019ils cr\u00e9e\u00adraient une nou\u00advelle soci\u00e9\u00adt\u00e9 d\u2019amour.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">C\u2019est un point impor\u00adtant que les nou\u00adveaux Dig\u00adgers aient d\u00e9bu\u00adt\u00e9 d\u2019une mani\u00e8re sem\u00adblable aux pre\u00admiers Dig\u00adgers \u2013 sim\u00adple\u00adment en mon\u00adtrant et en d\u00e9cla\u00adrant qu\u2019ils agis\u00adsaient en accord avec l\u2019esprit d\u2019un amour uni\u00adver\u00adsel. Le fait que cet amour \u00e9tait bas\u00e9 en par\u00adtie sur le LSD \u2013 et ne d\u00e9ri\u00advait pas de la Bible \u2013 n\u2019est pas cru\u00adcial. Les pre\u00admiers Dig\u00adgers se disaient \u00e9ga\u00adle\u00adment influen\u00adc\u00e9s par les id\u00e9es mys\u00adtiques, lors de leurs r\u00e9unions religieuses.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Au d\u00e9but, la venue des nou\u00adveaux Dig\u00adgers \u00e9tait lou\u00e9e par la com\u00admu\u00adnau\u00adt\u00e9 hip\u00adpy au com\u00adplet. Le \u00ab&nbsp;truc Dig\u00adger&nbsp;\u00bb de dis\u00adtri\u00adbuer des choses se r\u00e9pan\u00addit dans la com\u00admu\u00adnau\u00adt\u00e9 \u2013 et au-del\u00e0, dans les \u00e9coles et les uni\u00adver\u00adsi\u00adt\u00e9s de la ville. Lorsqu\u2019on cir\u00adcu\u00adlait dans Haight-Street et que l\u2019on voyait les gens dis\u00adtri\u00adbuer des fleurs, des fruits et des sucre\u00adries, il y avait dans l\u2019atmosph\u00e8re une nou\u00advelle force, puis\u00adsante. Les Dig\u00adgers, en un sens, deve\u00adnaient une nou\u00advelle men\u00adta\u00adli\u00adt\u00e9, \u00e0 l\u2019oppos\u00e9 de la men\u00adta\u00adli\u00adt\u00e9 mar\u00adchande, rapace du capi\u00adta\u00adlisme indus\u00adtriel. La posi\u00adtion morale des Dig\u00adgers n\u2019a pu \u00eatre vue en fait qu\u2019apr\u00e8s qu\u2019ils eurent \u00e9t\u00e9 \u00e9jec\u00adt\u00e9s de divers endroits par la police et le d\u00e9par\u00adte\u00adment de la san\u00adt\u00e9, et apr\u00e8s qu\u2019une \u00e9glise du voi\u00adsi\u00adnage eut don\u00adn\u00e9 le b\u00e9n\u00e9\u00adfice d\u2019une cui\u00adsine et d\u2019un bureau. Ils furent bien\u00adt\u00f4t consi\u00add\u00e9\u00adr\u00e9s comme la par\u00adtie de la com\u00admu\u00adnau\u00adt\u00e9 la plus belle et ils com\u00admen\u00adc\u00e8rent \u00e0 \u00eatre \u00e9ti\u00adque\u00adt\u00e9s par quelques-uns comme un \u00ab&nbsp;Ser\u00advice de la Com\u00admu\u00adnau\u00adt\u00e9&nbsp;\u00bb. C\u2019est \u00e0 ce moment qu\u2019eut lieu une in\u00e9vi\u00adtable rup\u00adture, car les Dig\u00adgers ne d\u00e9si\u00adraient pas \u00eatre un Ser\u00advice pour la com\u00admu\u00adnau\u00adt\u00e9 \u2013 ils vou\u00adlaient que la com\u00admu\u00adnau\u00adt\u00e9 elle-m\u00eame soit bas\u00e9e sur cette nou\u00advelle men\u00adta\u00adli\u00adt\u00e9. Un conflit \u00e9cla\u00adta entre les Dig\u00adgers et les mar\u00adchands du \u00ab&nbsp;hip&nbsp;\u00bb.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Il \u00e9tait clai\u00adre\u00adment \u00e9vident que les mar\u00adchands s\u2019enrichissaient sans aider les hip\u00adpies dans les rues, beau\u00adcoup d\u2019entre eux \u00e9taient \u00e0 la charge des Dig\u00adgers. A un mee\u00adting, un des Dig\u00adgers les plus en voix deman\u00adda pour\u00adquoi, s\u2019ils consti\u00adtuaient un Ser\u00advice pour la com\u00admu\u00adnau\u00adt\u00e9, trou\u00advaient-ils si dif\u00adfi\u00adcile d\u2019obtenir de l\u2019aide de la part de la com\u00admu\u00adnau\u00adt\u00e9. Ils sou\u00adhai\u00adtaient voir la mon\u00adnaie uti\u00adli\u00ads\u00e9e pour ache\u00adter de la place pour les gens \u2013 de la place pour vivre, de la place pour s\u2019agrandir, de la place pour cr\u00e9er le nou\u00adveau monde. De tels buts s\u2019opposaient \u00e0 ceux des mar\u00adchands, l\u2019esprit aux affaires. Une faille se d\u00e9ve\u00adlop\u00adpait \u00e0 tous les niveaux.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Pen\u00addant ce temps, la magie des Dig\u00adgers leur valut deux fermes qui sont main\u00adte\u00adnant ins\u00adtal\u00adl\u00e9es dans le but de four\u00adnir de la nour\u00adri\u00adture \u00e0 l\u2019avenir aus\u00adsi bien que comme colo\u00adnies de la liber\u00adt\u00e9. En avril 1967, le mou\u00adve\u00adment fran\u00adchit une bar\u00adri\u00e8re eth\u00adnique en \u00e9ta\u00adblis\u00adsant au c\u0153ur du ghet\u00adto noir un Maga\u00adsin Libre des Noirs (\u00ab&nbsp;Black Man\u2019s Free Store&nbsp;\u00bb). Ce fut \u00e0 ce moment \u2013 avec l\u2019installation de maga\u00adsins libres dans la com\u00admu\u00adnau\u00adt\u00e9 noire et dans Haight-Ash\u00adbu\u00adry, avec le d\u00e9but des fermes et la rup\u00adture avec les mar\u00adchands \u2013 que les Dig\u00adgers reprirent la voie de Wins\u00adtan\u00adley en met\u00adtant l\u2019accent sur des faits poli\u00adtiques concrets. Ils par\u00adlaient main\u00adte\u00adnant de la n\u00e9ces\u00adsi\u00adt\u00e9 de quelque r\u00e9vo\u00adlu\u00adtion \u2013 et sp\u00e9\u00adcia\u00adle\u00adment dans le Black Man\u2019s Free Store le tra\u00advail est envi\u00adsa\u00adg\u00e9 comme le d\u00e9but d\u2019une r\u00e9volution.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Ce nou\u00adveau style peut \u00eatre mieux rela\u00adt\u00e9 en se r\u00e9f\u00e9\u00adrant \u00e0 la conclu\u00adsion d\u2019un tract dig\u00adger dis\u00adtri\u00adbu\u00e9 au d\u00e9but mai 1967&nbsp;: \u00ab&nbsp;\u2026 Le bel amour est un seau d\u2019eau sale et nous sommes les enfants qui en ont conscience, mais notre cou\u00adrage ne s\u2019est pas encore mani\u00adfes\u00adt\u00e9 \u00e0 l\u2019int\u00e9rieur de notre com\u00admu\u00adnau\u00adt\u00e9 flot\u00adtante. Nous avons rabrou\u00e9 les mar\u00adchands, les emmer\u00addeurs, les arri\u00advistes, et nous nous sommes assis, et c\u2019est tout comme avant, et il n\u2019y a rien de nou\u00adveau sous le soleil, et la nour\u00adri\u00adture gra\u00adtuite semble long\u00adtemps \u00eatre venue parce que nous jouons au jeu des ann\u00e9es 30, parce que nous sommes les nou\u00adveaux pleur\u00adni\u00adcheurs, et les larmes de James Dean ont fina\u00adle\u00adment pris racine dans une s\u00e9rie de cabales aux besoins faibles et super\u00adfi\u00adciels qui attendent quelqu\u2019un pour prendre soin de leur mode de vie\u2026 quelle r\u00e9volution.&nbsp;\u00bb<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Ceci ne sous-entend pas que les Dig\u00adgers renoncent \u00e0 l\u2019amour. Et m\u00eame il y a plus d\u2019amour main\u00adte\u00adnant qu\u2019auparavant. Mais ils deviennent davan\u00adtage conscients de la force du capi\u00adta\u00adlisme indus\u00adtriel dans la com\u00adp\u00e9\u00adti\u00adtion depuis qu\u2019il menace leur propre com\u00admu\u00adnau\u00adt\u00e9. Cette conscience fut d\u00e9mon\u00adtr\u00e9e lorsque quatre indi\u00advi\u00addus li\u00e9s aux Dig\u00adgers, cha\u00adcun d\u2019un quar\u00adtier dif\u00adf\u00e9\u00adrent de San Fran\u00adcis\u00adco, envoy\u00e8rent une lettre \u00e0 l\u2019administration de la ville \u2013 lettre fai\u00adsant \u00e9cho \u00e0 la requ\u00eate de Wins\u00adtan\u00adley et deman\u00addant un sys\u00adt\u00e8me de libres entre\u00adp\u00f4ts ren\u00adflou\u00e9s d\u00e8s que vides. La lettre arguait que notre sys\u00adt\u00e8me indus\u00adtriel est capable de nour\u00adrir qui\u00adconque s\u2019il est orga\u00adni\u00ads\u00e9 dans cette inten\u00adtion, et elle d\u00e9cla\u00adrait qu\u2019il s\u2019agissait d\u2019une n\u00e9ces\u00adsi\u00adt\u00e9 morale et psy\u00adcho\u00adlo\u00adgique. Lisant ce tract dans le Black Man\u2019s Free Store, fixant \u00e0 tra\u00advers la fen\u00eatre les pros\u00adti\u00adtu\u00e9es qui ven\u00addaient leurs corps (de beaux corps noirs par un apr\u00e8s-midi enso\u00adleill\u00e9), je r\u00e9a\u00adli\u00adsais que de tels chan\u00adge\u00adments \u00e9taient bien n\u00e9ces\u00adsaires. Mais les Dig\u00adgers ne pou\u00advaient seuls les accom\u00adplir. Il fau\u00addrait une alliance mas\u00adsive des jeunes \u00ab&nbsp;ali\u00e9\u00adn\u00e9s&nbsp;\u00bb et de la gauche politique.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Cepen\u00addant, les Dig\u00adgers conti\u00adnuent \u00e0 tra\u00advailler dans leur direc\u00adtion \u2013 \u00e0 tra\u00advailler \u00e0 tra\u00advers l\u2019interm\u00e9diaire de l\u2019amour, ain\u00adsi que l\u2019illustrait le dia\u00adlogue sui\u00advant enten\u00addu dans le Black Mans Free Store, alors qu\u2019il ouvrait, en&nbsp;avril&nbsp;:<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Rem\u00adbrandt (un peintre d\u2019enseignes pas\u00adsant par-l\u00e0)&nbsp;: Je vois, mecs, que vous ouvrez un maga\u00adsin. Vou\u00adlez-vous faire peindre une enseigne&nbsp;?<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Roy (un ancien \u00ab&nbsp;com\u00adbat\u00adtant de la liber\u00adt\u00e9&nbsp;\u00bb au Mis\u00adsis\u00adsip\u00adpi, main\u00adte\u00adnant l\u2019organisateur du maga\u00adsin)&nbsp;: Oui&nbsp;; c\u2019est un maga\u00adsin gra\u00adtuit, aus\u00adsi ne pou\u00advons-nous pas te payer, mais si tu veux peindre une enseigne\u2026 tu vois, nous dis\u00adtri\u00adbuons des choses.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Rem\u00adbrandt&nbsp;: Je ne donne jamais rien et per\u00adsonne ne m\u2019a jamais don\u00adn\u00e9 quoi que ce&nbsp;soit.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Roy&nbsp;: Per\u00adsonne ne t\u2019a jamais don\u00adn\u00e9 quelque chose&nbsp;?\u2026 Regarde cette bo\u00eete de pein\u00adtures au pis\u00adto\u00adlet \u2013 si tu peux les uti\u00adli\u00adser, elles sont \u00e0 toi. As-tu de l\u2019argent&nbsp;? Voi\u00adci trente sous pour payer le&nbsp;bus.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Rem\u00adbrandt&nbsp;: Je ne com\u00adprends pas. Qu\u2019est-ce que vous faites ici,&nbsp;mecs&nbsp;?<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Roy&nbsp;: Regarde ce grand maga\u00adsin d\u2019appareils et de mobi\u00adlier de l\u2019autre c\u00f4t\u00e9 de la rue, avec ce pan\u00adneau indi\u00adquant qu\u2019on encaisse les bons d\u2019achat&nbsp;? Bien, c\u2019est l\u00e0 o\u00f9 vont tous les gens qui vivent avec ces bons\u2026 Je les y ai conduits moi-m\u00eame. La femme qui tient la bou\u00adtique est venue ici il y a un moment deman\u00adder ce que nous fai\u00adsions. Quand je lui ai dit que nous \u00e9ta\u00adblis\u00adsions un maga\u00adsin gra\u00adtuit, elle me dit que je me trou\u00advais dans un mau\u00advais coin \u2013 que nous n\u2019avions pas besoin d\u2019un maga\u00adsin gra\u00adtuit ici. Elle dit que je devais aller \u00e0 Haight-Ash\u00adbu\u00adry. Alors elle s\u2019excita vrai\u00adment et dit que nous ne pou\u00advions pas faire ceci ici et qu\u2019elle l\u2019emp\u00eacherait. Oui, nous nous pro\u00adpo\u00adsons de dis\u00adtri\u00adbuer ici des choses de sorte que les gens qui vivent des bons d\u2019achat puissent avoir assez d\u2019argent pour vivre mieux que main\u00adte\u00adnant. C\u2019est le d\u00e9but d\u2019un mou\u00adve\u00adment r\u00e9volutionnaire.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Rem\u00adbrandt&nbsp;: Je vois. Pour\u00adquoi est-ce que je ne pein\u00addrais pas une belle et grande enseigne sur la vitre disant&nbsp;: \u00ab&nbsp;Guet\u00adtez notre grand jour d\u2019ouverture&nbsp;\u00bb et j\u2019\u00e9crirais&nbsp;: \u00ab&nbsp;Nour\u00adri\u00adture, v\u00eate\u00adments et appa\u00adreils gra\u00adtuits&nbsp;\u00bb \u2013 ceci effa\u00adre\u00adra vrai\u00adment la&nbsp;femme.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Rem\u00adbrandt (apr\u00e8s avoir peint)&nbsp;: \u00c9coute, j\u2019ai un camion que je peux emprun\u00adter, aus\u00adsi je retour\u00adne\u00adrai, je vous don\u00adne\u00adrai un coup de main et je vous aide\u00adrai \u00e0 trans\u00adpor\u00adter quelques affaires.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">(Il s\u2019en&nbsp;va.)<\/p>\n<p lang=\"fr-FR\" style=\"text-align: justify;\" align=\"justify\">Roy&nbsp;: Il a r\u00e9el\u00adle\u00adment r\u00e9us\u00adsi son truc, n\u2019est-ce pas&nbsp;? Aviez-vous creu\u00ads\u00e9 le ter\u00adrain&nbsp;? Nous avons ame\u00adn\u00e9 ce malin \u00e0 faire son truc et il l\u2019a fait, tiens, il l\u2019a vrai\u00adment&nbsp;fait.<\/p>\n<p lang=\"fr-FR\" style=\"text-align: right;\" align=\"justify\">Alex For\u00adman<br>\n(\u00ab&nbsp;Anar\u00adchy&nbsp;\u00bb, num\u00e9\u00adro 77, juillet 1967.)<\/p>\n<ul class=\"modern-footnotes-list modern-footnotes-list--show-only-for-print\"><li><span>1<\/span><div>Docu\u00admen\u00adta\u00adtion de base dans \u00ab&nbsp;La Paix cr\u00e9a\u00adtrice&nbsp;\u00bb (tome II) de Bar\u00adth\u00e9\u00adle\u00admy de&nbsp;Ligt.<\/div><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Quand un petit groupe d\u2019hommes com\u00admen\u00ad\u00e7a \u00e0 retour\u00adner (dig) la terre et \u00e0 plan\u00adter sur les ter\u00adrains com\u00admu\u00adnaux de St. Georges Hill dans le Sur\u00adrey en 1649, ce fut le point culmi\u00adnant et radi\u00adcal des nou\u00advelles forces de chan\u00adge\u00adment qui r\u00e9sul\u00adtaient de la R\u00e9forme dans l\u2019Empire Ger\u00adma\u00adnique. Car avec l\u2019effondrement de la supr\u00e9\u00adma\u00adtie totale de&nbsp;[\u2026]<\/p>\n","protected":false},"author":1,"featured_media":5488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"wp-custom-template-page-d-article","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[112],"tags":[],"ppma_author":[540],"class_list":["post-951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anarchisme-et-non-violence-na11-12-janvier-fevrier-1968"],"authors":[{"term_id":540,"user_id":1,"is_guest":0,"slug":"admin_3gikpwyf","display_name":"Vincent Dubuc","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/d015720652c25fd2ced191ade86430094e1f288a17483713e3b34d26dea52507?s=96&d=mm&r=g","author_category":"","user_url":"https:\/\/la-presse-anarchiste.net","last_name":"Dubuc","first_name":"Vincent","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/comments?post=951"}],"version-history":[{"count":3,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/951\/revisions"}],"predecessor-version":[{"id":5527,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/posts\/951\/revisions\/5527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/media\/5488"}],"wp:attachment":[{"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/media?parent=951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/categories?post=951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/tags?post=951"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/la-presse-anarchiste.net\/index.php\/wp-json\/wp\/v2\/ppma_author?post=951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}